{"id":41452,"date":"2025-01-21T12:59:29","date_gmt":"2025-01-21T12:59:29","guid":{"rendered":"https:\/\/www.agrikomp.com\/?p=41452"},"modified":"2025-01-21T14:05:56","modified_gmt":"2025-01-21T14:05:56","slug":"actu-salon-2025-02-bio360","status":"publish","type":"post","link":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/","title":{"rendered":"BIO360  \u2758  STAND D73  \u2758  05-06\/02\/2025 \u00e0 Nantes (44)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"41452\" class=\"elementor elementor-41452\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2feefad elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2feefad\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7167bf\" data-id=\"e7167bf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-717bf03d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"717bf03d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b59dc3b\" data-id=\"5b59dc3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58e50515 elementor-widget elementor-widget-spacer\" data-id=\"58e50515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-33b5f162 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33b5f162\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cb6eff9\" data-id=\"1cb6eff9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e38523 elementor-widget elementor-widget-image\" data-id=\"7e38523\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"320\" src=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AFR_BIO360_banniere_0225-1-1024x409.png\" class=\"attachment-large size-large wp-image-41468\" alt=\"\" srcset=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AFR_BIO360_banniere_0225-1-1024x409.png 1024w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/AFR_BIO360_banniere_0225-1-300x120.png 300w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/AFR_BIO360_banniere_0225-1-768x307.png 768w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/AFR_BIO360_banniere_0225-1.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-70d98c2f\" data-id=\"70d98c2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4591d9 elementor-widget elementor-widget-heading\" data-id=\"f4591d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le SALON BIO360 EXPO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f39ce1 elementor-widget elementor-widget-text-editor\" data-id=\"57f39ce1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"57f39ce1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div>\n<div>\n<p>Les 05 &amp; 06 f\u00e9vrier, retrouvez-nous \u00e0 Nantes, au salon Bio360 Expo!<\/p>\n<p>Venez \u00e0 notre rencontre, nous serons ravis d\u2019\u00e9changer avec vous sur vos projets de m\u00e9thanisation, en cog\u00e9n\u00e9ration comme en injection biom\u00e9thane!<\/p>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c57d829 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c57d829\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fca52a9\" data-id=\"fca52a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bee50e7 elementor-widget elementor-widget-text-editor\" data-id=\"bee50e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2026 6 salles de conf\u00e9rences bilingues<br \/>\u2026 2 jours de salon<br \/>&#8230; entre 450 et 500 exposants<\/p><p><img decoding=\"async\" src=\"https:\/\/www.facebook.com\/images\/emoji.php\/v9\/t25\/1.5\/16\/27a1.png\" alt=\"\u27a1\" width=\"16\" height=\"16\" \/> Plus de 20 conf\u00e9rences sur les th\u00e8mes du biogaz, du transport bas carbone de la d\u00e9carbonation ou encore de la biomasse.<\/p><p><strong>Les visiteurs du Salon ont libre acc\u00e8s \u00e0 toutes les conf\u00e9rences.<\/strong><\/p><p>Une traduction simultan\u00e9e anglais\/fran\u00e7ais est propos\u00e9e tout au long du programme des conf\u00e9rences et pendant les 2 jours, mais n\u2019oubliez pas d\u2019apporter vos \u00e9couteurs, votre t\u00e9l\u00e9phone portable et une batterie externe.<br \/>Sur place, vous pourrez acc\u00e9der \u00e0 la traduction simultan\u00e9e<br \/>en scannant un QRcode qui n\u2019implique aucun t\u00e9l\u00e9chargement ni<br \/>installation de logiciel sur votre appareil mobile mais vous permettra<br \/>de basculer en toute simplicit\u00e9 entre le fran\u00e7ais et l\u2019anglais via une<br \/>plateforme d\u00e9di\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca4ab02\" data-id=\"ca4ab02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2e7193 elementor-widget elementor-widget-text-editor\" data-id=\"f2e7193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Bio\u00e9nergie solide<\/li>\n<li>Bio\u00e9nergie liquide<\/li>\n<li>Bio\u00e9nergie gazeuse<\/li>\n<li>Mat\u00e9riaux et produits biosourc\u00e9s<\/li>\n<li>Biochar<\/li>\n<li>Capture et utilisation \/ stockage du carbone (CCU\/S)<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.bio360expo.com\/Page\/1260\/programme-2024\" target=\"_blank\" rel=\"noopener\"><strong>&gt; Acc\u00e9dez au programme complet des conf\u00e9rences<\/strong><\/a><\/p>\n<p>L\u2019objectif unique de <a href=\"https:\/\/www.bio360expo.com\/Page\/1024\/pourquoi-visiter\" target=\"_blank\" rel=\"noopener\">Bio360 Expo<\/a> est de participer \u00e0 l\u2019effort mondial pour pr\u00e9server notre plan\u00e8te <strong>en acc\u00e9l\u00e9rant la biotransition<\/strong>.<\/p>\n<p>C\u2019est un <strong>lieu de rencontre international<\/strong> pour les personnes et les organisations qui partagent une implication dans cette mission et qui ont hiss\u00e9 ou souhaitent hisser leurs couleurs au m\u00e2t de la biotransition.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-662c60d elementor-widget elementor-widget-spacer\" data-id=\"662c60d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68aea47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68aea47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-404e5bc\" data-id=\"404e5bc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4791a29 elementor-widget elementor-widget-spacer\" data-id=\"4791a29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb48c98 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"bb48c98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rendez-vous \u00e0 BIO360<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56c61cb elementor-widget elementor-widget-heading\" data-id=\"56c61cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">STAND D 73<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2907d9d elementor-widget elementor-widget-spacer\" data-id=\"2907d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6554dd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6554dd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5ed61a\" data-id=\"f5ed61a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c76c091 elementor-widget elementor-widget-spacer\" data-id=\"c76c091\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4d68f0 elementor-widget elementor-widget-heading\" data-id=\"d4d68f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Infos utiles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c99770b elementor-widget elementor-widget-spacer\" data-id=\"c99770b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4c07f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4c07f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bef307c\" data-id=\"bef307c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c9fe717 elementor-widget elementor-widget-text-editor\" data-id=\"4c9fe717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dates &amp; Horaires :<\/strong><\/p>\n<ul>\n<li>mardi 05 f\u00e9vrier, de 9h \u00e0 18h<\/li>\n<li>mercredi 06 f\u00e9vrier, de 9h \u00e0 17h<\/li>\n<\/ul>\n<p><strong>Lieu : <br \/><\/strong>ExpoNantes, Parc des Expositions, Hall XXL &#8211; France<\/p>\n<p><strong>Hall : XXL &#8211; Stand : D 73<br \/><\/strong><\/p>\n<p>Site internet du salon : <a href=\"https:\/\/www.bio360expo.com\/\" target=\"_blank\" rel=\"noopener\" data-auto-event-observed=\"true\">BIO360 EXPO<\/a><\/p>\n<p>\u2705 <a href=\"https:\/\/www.bio360expo.com\/form\/542?aid=1037\" target=\"_blank\" rel=\"noopener\" data-auto-event-observed=\"true\">Inscrivez-vous ici pour obtenir votre entr\u00e9e visiteur gratuite<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48b18eb elementor-widget elementor-widget-image\" data-id=\"48b18eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/bio360-banniere-1-300x300.png\" class=\"attachment-medium size-medium wp-image-41492\" alt=\"\" srcset=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/bio360-banniere-1-300x300.png 300w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/bio360-banniere-1-150x150.png 150w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/bio360-banniere-1-768x768.png 768w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/bio360-banniere-1.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c2d283e\" data-id=\"c2d283e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e43abf7 elementor-widget elementor-widget-google_maps\" data-id=\"e43abf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"google-maps\" data-borlabs-cookie-content=\"PGlmcmFtZSBsb2FkaW5nPSJsYXp5IgoJCQkJCXNyYz0iaHR0cHM6Ly9tYXBzLmdvb2dsZS5jb20vbWFwcz9xPXBhcmMlMjBkZXMlMjBleHBvc2l0aW9ucyUyQyUyMG5hbnRlcyYjMDM4O3Q9bSYjMDM4O3o9MTMmIzAzODtvdXRwdXQ9ZW1iZWQmIzAzODtpd2xvYz1uZWFyIgoJCQkJCXRpdGxlPSJwYXJjIGRlcyBleHBvc2l0aW9ucywgbmFudGVzIgoJCQkJCWFyaWEtbGFiZWw9InBhcmMgZGVzIGV4cG9zaXRpb25zLCBuYW50ZXMiCgkJCT48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-b brlbs-cmpnt-cb-google-maps\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.agrikomp.com\/wp-content\/uploads\/borlabs-cookie\/1\/brlbs-cb-google-maps-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Vous \u00eates actuellement en train de consulter le contenu d'un espace r\u00e9serv\u00e9 de <strong>Google Maps<\/strong>. Pour acc\u00e9der au contenu r\u00e9el, cliquez sur le bouton ci-dessous. Veuillez noter que ce faisant, des donn\u00e9es seront partag\u00e9es avec des providers tiers.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Plus d'informations<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">D\u00e9bloquer le contenu<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Accepter le service requis et d\u00e9bloquer les contenus<\/a> <\/div> <\/div> <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4e5239 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4e5239\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01c491a\" data-id=\"01c491a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a11b85 elementor-widget elementor-widget-spacer\" data-id=\"5a11b85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bc55620 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc55620\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86f0ebe\" data-id=\"86f0ebe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0a3f40 elementor-widget elementor-widget-text-editor\" data-id=\"d0a3f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pr\u00e9parez d&#8217;ores et d\u00e9j\u00e0 votre visite au salon Bio360, avec, par exemple, l&#8217;organisation de covoiturage !<\/p>\n<p><a href=\"https:\/\/www.bio360expo.com\/Page\/1008\/infos-pratiques\" target=\"_blank\" rel=\"noopener\">&gt; Toutes les infos pratiques<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb7c8d4\" data-id=\"cb7c8d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8eb4747 elementor-widget elementor-widget-text-editor\" data-id=\"8eb4747\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lors de ce salon, vous aurez l&#8217;occasion de discuter avec notre technico-commercial <strong>sp\u00e9cialiste de la m\u00e9thanisation, Sylvain, <\/strong>ou encore notre service <strong>Marketing &amp; Communication <\/strong>ainsi que notre service<strong> Moteur ServiceUnion <\/strong>!<\/p>\n<p>N&#8217;attendez-plus : <a href=\"https:\/\/www.bio360expo.com\/form\/542?aid=1037\" target=\"_blank\" rel=\"noopener\" data-auto-event-observed=\"true\">prenez vos places !<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fccd786 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fccd786\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9315cc2\" data-id=\"9315cc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f690a30 elementor-widget elementor-widget-spacer\" data-id=\"f690a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-152cca2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"152cca2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d63fb6a\" data-id=\"d63fb6a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffada72 elementor-widget elementor-widget-spacer\" data-id=\"ffada72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64e4ca8 elementor-widget elementor-widget-heading\" data-id=\"64e4ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Retrouvez toutes nos actualit\u00e9s ici :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d502507 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d502507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/agrikomp.com\/fr\/vous-et-nous\/le-saviez-vous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">L'ACTU AGRIKOMP <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16bbdc0 elementor-widget elementor-widget-spacer\" data-id=\"16bbdc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le SALON BIO360 EXPO Les 05 &amp; 06 f\u00e9vrier, retrouvez-nous \u00e0 Nantes, au salon Bio360 Expo! Venez \u00e0 notre rencontre, nous serons ravis d\u2019\u00e9changer avec vous sur vos projets de m\u00e9thanisation, en cog\u00e9n\u00e9ration comme en injection biom\u00e9thane! \u2026 6 salles de conf\u00e9rences bilingues\u2026 2 jours de salon&#8230; entre 450 et 500 exposants Plus de 20 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":29556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[216],"tags":[],"class_list":["post-41452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BIO360 \u2758 STAND D73 \u2758 05-06\/02\/2025 \u00e0 Nantes (44) - agriKomp<\/title>\n<meta name=\"description\" content=\"Rendez-vous sur le salon BIO360 pour \u00e9changer avec le sp\u00e9cialiste de la m\u00e9thanisation agricole sur vos projets cog\u00e9n\u00e9ration et biom\u00e9thane.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BIO360 \u2758 STAND D73 \u2758 05-06\/02\/2025 \u00e0 Nantes (44)\" \/>\n<meta property=\"og:description\" content=\"Rendez-vous sur le salon BIO360 pour \u00e9changer avec le sp\u00e9cialiste de la m\u00e9thanisation agricole sur vos projets cog\u00e9n\u00e9ration et biom\u00e9thane.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/\" \/>\n<meta property=\"og:site_name\" content=\"agriKomp GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agriKomp.Deutschland\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T12:59:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T14:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AKFR_WEB_2302_actu-BIO360_335x300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"335\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marketing France\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing France\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/\"},\"author\":{\"name\":\"Marketing France\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#\\\/schema\\\/person\\\/258cf5603b1b50c8028600dad2d48c35\"},\"headline\":\"BIO360 \u2758 STAND D73 \u2758 05-06\\\/02\\\/2025 \u00e0 Nantes (44)\",\"datePublished\":\"2025-01-21T12:59:29+00:00\",\"dateModified\":\"2025-01-21T14:05:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/\"},\"wordCount\":388,\"publisher\":{\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/AKFR_WEB_2302_actu-BIO360_335x300.jpg\",\"articleSection\":[\"Ev\u00e9nements\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/\",\"url\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/\",\"name\":\"BIO360 \u2758 STAND D73 \u2758 05-06\\\/02\\\/2025 \u00e0 Nantes (44) - agriKomp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/AKFR_WEB_2302_actu-BIO360_335x300.jpg\",\"datePublished\":\"2025-01-21T12:59:29+00:00\",\"dateModified\":\"2025-01-21T14:05:56+00:00\",\"description\":\"Rendez-vous sur le salon BIO360 pour \u00e9changer avec le sp\u00e9cialiste de la m\u00e9thanisation agricole sur vos projets cog\u00e9n\u00e9ration et biom\u00e9thane.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/AKFR_WEB_2302_actu-BIO360_335x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/AKFR_WEB_2302_actu-BIO360_335x300.jpg\",\"width\":335,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/actu-salon-2025-02-bio360\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ev\u00e9nements\",\"item\":\"https:\\\/\\\/www.agrikomp.com\\\/fr\\\/category\\\/evenements\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BIO360 \u2758 STAND D73 \u2758 05-06\\\/02\\\/2025 \u00e0 Nantes (44)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/\",\"name\":\"agriKomp GmbH\",\"description\":\"Biogasanlagen und Biogastechnik wie sie gebraucht wird\",\"publisher\":{\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#organization\",\"name\":\"agriKomp\",\"url\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/150224_aKlogo-grau_quer.png\",\"contentUrl\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/150224_aKlogo-grau_quer.png\",\"width\":2712,\"height\":482,\"caption\":\"agriKomp\"},\"image\":{\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agriKomp.Deutschland\",\"https:\\\/\\\/www.instagram.com\\\/agrikomp\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/5254243\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@AgrikompDeutschland\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#\\\/schema\\\/person\\\/258cf5603b1b50c8028600dad2d48c35\",\"name\":\"Marketing France\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BIO360 \u2758 STAND D73 \u2758 05-06\/02\/2025 \u00e0 Nantes (44) - agriKomp","description":"Rendez-vous sur le salon BIO360 pour \u00e9changer avec le sp\u00e9cialiste de la m\u00e9thanisation agricole sur vos projets cog\u00e9n\u00e9ration et biom\u00e9thane.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/","og_locale":"fr_FR","og_type":"article","og_title":"BIO360 \u2758 STAND D73 \u2758 05-06\/02\/2025 \u00e0 Nantes (44)","og_description":"Rendez-vous sur le salon BIO360 pour \u00e9changer avec le sp\u00e9cialiste de la m\u00e9thanisation agricole sur vos projets cog\u00e9n\u00e9ration et biom\u00e9thane.","og_url":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/","og_site_name":"agriKomp GmbH","article_publisher":"https:\/\/www.facebook.com\/agriKomp.Deutschland","article_published_time":"2025-01-21T12:59:29+00:00","article_modified_time":"2025-01-21T14:05:56+00:00","og_image":[{"width":335,"height":300,"url":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AKFR_WEB_2302_actu-BIO360_335x300.jpg","type":"image\/jpeg"}],"author":"Marketing France","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marketing France","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/#article","isPartOf":{"@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/"},"author":{"name":"Marketing France","@id":"https:\/\/agrikomp.com\/de\/#\/schema\/person\/258cf5603b1b50c8028600dad2d48c35"},"headline":"BIO360 \u2758 STAND D73 \u2758 05-06\/02\/2025 \u00e0 Nantes (44)","datePublished":"2025-01-21T12:59:29+00:00","dateModified":"2025-01-21T14:05:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/"},"wordCount":388,"publisher":{"@id":"https:\/\/agrikomp.com\/de\/#organization"},"image":{"@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/#primaryimage"},"thumbnailUrl":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AKFR_WEB_2302_actu-BIO360_335x300.jpg","articleSection":["Ev\u00e9nements"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/","url":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/","name":"BIO360 \u2758 STAND D73 \u2758 05-06\/02\/2025 \u00e0 Nantes (44) - agriKomp","isPartOf":{"@id":"https:\/\/agrikomp.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/#primaryimage"},"image":{"@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/#primaryimage"},"thumbnailUrl":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AKFR_WEB_2302_actu-BIO360_335x300.jpg","datePublished":"2025-01-21T12:59:29+00:00","dateModified":"2025-01-21T14:05:56+00:00","description":"Rendez-vous sur le salon BIO360 pour \u00e9changer avec le sp\u00e9cialiste de la m\u00e9thanisation agricole sur vos projets cog\u00e9n\u00e9ration et biom\u00e9thane.","breadcrumb":{"@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/#primaryimage","url":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AKFR_WEB_2302_actu-BIO360_335x300.jpg","contentUrl":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/AKFR_WEB_2302_actu-BIO360_335x300.jpg","width":335,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.agrikomp.com\/fr\/actu-salon-2025-02-bio360\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.agrikomp.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Ev\u00e9nements","item":"https:\/\/www.agrikomp.com\/fr\/category\/evenements\/"},{"@type":"ListItem","position":3,"name":"BIO360 \u2758 STAND D73 \u2758 05-06\/02\/2025 \u00e0 Nantes (44)"}]},{"@type":"WebSite","@id":"https:\/\/agrikomp.com\/de\/#website","url":"https:\/\/agrikomp.com\/de\/","name":"agriKomp GmbH","description":"Biogasanlagen und Biogastechnik wie sie gebraucht wird","publisher":{"@id":"https:\/\/agrikomp.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrikomp.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/agrikomp.com\/de\/#organization","name":"agriKomp","url":"https:\/\/agrikomp.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/agrikomp.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/11\/150224_aKlogo-grau_quer.png","contentUrl":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/11\/150224_aKlogo-grau_quer.png","width":2712,"height":482,"caption":"agriKomp"},"image":{"@id":"https:\/\/agrikomp.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agriKomp.Deutschland","https:\/\/www.instagram.com\/agrikomp\/?hl=en","https:\/\/www.linkedin.com\/company\/5254243\/","https:\/\/www.youtube.com\/@AgrikompDeutschland"]},{"@type":"Person","@id":"https:\/\/agrikomp.com\/de\/#\/schema\/person\/258cf5603b1b50c8028600dad2d48c35","name":"Marketing France"}]}},"_links":{"self":[{"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/posts\/41452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/comments?post=41452"}],"version-history":[{"count":4,"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/posts\/41452\/revisions"}],"predecessor-version":[{"id":41500,"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/posts\/41452\/revisions\/41500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/media\/29556"}],"wp:attachment":[{"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/media?parent=41452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/categories?post=41452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agrikomp.com\/fr\/wp-json\/wp\/v2\/tags?post=41452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}