{"id":105,"date":"2020-11-16T14:46:34","date_gmt":"2020-11-16T14:46:34","guid":{"rendered":"https:\/\/agrikomp.com\/?page_id=105"},"modified":"2024-12-18T09:43:03","modified_gmt":"2024-12-18T09:43:03","slug":"dienstleistungen","status":"publish","type":"page","link":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/","title":{"rendered":"Dienstleistungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"105\" class=\"elementor elementor-105\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-756eb9dc elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"756eb9dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.2,&quot;sizes&quot;:[]}}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b50fd31\" data-id=\"7b50fd31\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24967b97 elementor-widget elementor-widget-spacer\" data-id=\"24967b97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ce484f\" data-id=\"3ce484f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dea6f15 elementor-widget elementor-widget-heading\" data-id=\"3dea6f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Dienstleistungen<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42ce72fe elementor-widget elementor-widget-heading\" data-id=\"42ce72fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Serviceleistungen vom ersten Tag an<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ddfafaf elementor-widget elementor-widget-text-editor\" data-id=\"3ddfafaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Legt man eine Laufzeit von mindestens 20 Jahren f\u00fcr eine Biogasanlage zu Grunde, dann wird deutlich, welchen Stellenwert ein zuverl\u00e4ssiger Servicepartner f\u00fcr das Betriebsergebnis hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-22639bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22639bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8fe70e0\" data-id=\"8fe70e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8efbbb9 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"8efbbb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"#dienstleistungen21B2\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DIENSTLEISTUNGEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f92e6ab\" data-id=\"f92e6ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a51abff elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a51abff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#serviceunion21B2\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SERVICEUNION<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fe29d08\" data-id=\"fe29d08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d856cb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5d856cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#finanzierung21B2\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">FINANZIERUNG<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d308ec5\" data-id=\"d308ec5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0992db6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0992db6\" data-element_type=\"section\" data-e-type=\"section\" id=\"dienstleistungen21B2\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2dde8ee\" data-id=\"2dde8ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb57353 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"cb57353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-07b3426 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07b3426\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc55909\" data-id=\"dc55909\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4df6982 elementor-widget elementor-widget-heading\" data-id=\"4df6982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">ALLES AUS EINER HAND \u2013 <br \/>DARAUF IST VERLASS!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab85e12 elementor-widget elementor-widget-text-editor\" data-id=\"ab85e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Langfristig entscheiden hochwertige Technik, zuverl\u00e4ssiger Service und konti\u00adnuierliche Updates \u00fcber die Rentabilit\u00e4t Ihrer Biogasanlage. In Sachen \u201eUpdates\u201c verstehen wir bei agriKomp nicht nur technische und biologische Innovationen und Verbesserungen, sondern auch die kontinuierliche Weiter\u00adentwicklung und Vertiefung des Know-hows unserer Mitarbeiter.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8be55a4 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"8be55a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0cad0e6\" data-id=\"0cad0e6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0dbed2 elementor-widget elementor-widget-spacer\" data-id=\"a0dbed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-be366ef elementor-widget elementor-widget-spacer\" data-id=\"be366ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6551b2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6551b2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8eefc80\" data-id=\"8eefc80\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0495d2f elementor-widget elementor-widget-spacer\" data-id=\"0495d2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41624dc\" data-id=\"41624dc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88346d7 elementor-widget elementor-widget-heading\" data-id=\"88346d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">GR\u00dcNDLICH GESCHULTE SPEZIALISTEN \u2013 HOCH MOTIVIERT!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d12cc4 elementor-widget elementor-widget-text-editor\" data-id=\"4d12cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Viele unserer Mitarbeiter kommen aus der Landwirtschaft oder sind eng mit ihr verbunden. Unsere Teams durchlaufen regelm\u00e4\u00dfige Schulungs- und Trainingsprogramme. Dabei legen wir besonderen Wert darauf, dass unsere Spezialisten auch alle Arbeitsabl\u00e4ufe beim Betrieb einer Biogasanlage verstehen. Dar\u00fcber hinaus stellt die Modelltreue unserer Anlagentechnik sicher, dass jeder Griff \u201csitzt\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b91887 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"1b91887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fa675eb elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa675eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b30fa1d\" data-id=\"b30fa1d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12dd522 elementor-widget elementor-widget-heading\" data-id=\"12dd522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">STANDARDISIERTE TECHNIK \u2013 SICHER VERSORGT!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fa5c3b elementor-widget elementor-widget-text-editor\" data-id=\"8fa5c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Beim Technikeinsatz setzen wir auf solide Qualit\u00e4t und Langlebigkeit. Der hohe Standardisierungsgrad unserer Anlagen und Komponenten stellt eine langfristige und zuverl\u00e4ssige Ersatzteilversorgung sicher. Ein umfangreiches und zentral gelegenes Materialdepot sorgt von der kleinsten Schraube bis zum kompletten BHKW f\u00fcr zuverl\u00e4ssige Ersatzteilverf\u00fcgbarkeit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11d6b8e\" data-id=\"11d6b8e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7524e1 elementor-widget elementor-widget-spacer\" data-id=\"d7524e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfc0b19 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"dfc0b19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82160f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82160f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c78e85\" data-id=\"7c78e85\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a08529 elementor-widget elementor-widget-spacer\" data-id=\"0a08529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-87e9dc6\" data-id=\"87e9dc6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8295265 elementor-widget elementor-widget-heading\" data-id=\"8295265\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">NAH BEI IHNEN \u2013 <br \/>\nKURZE REAKTIONSZEITEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5ee132 elementor-widget elementor-widget-text-editor\" data-id=\"d5ee132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Im Notfall muss es ganz schnell gehen! Egal wie viele Kilometer zwischen uns liegen. Unsere Servicemitarbeiter an den Terminals k\u00f6nnen schnell per Fernwartung analysieren und Fehler beheben. Dar\u00fcber hinaus stehen mobile Teams an dicht vernetzten, regionalen Servicest\u00fctzpunkten bereit. <br \/>Im Innendienst arbeiten die Teams von BHKW-, Anlagen-Service und Ersatzteillager im Zwei-Schichten-System an sieben Tagen in der Woche! Die technische Rufbereitschaft an Wochenenden und Feiertagen ist f\u00fcr uns selbstverst\u00e4ndlich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb6378a elementor-widget elementor-widget-spacer\" data-id=\"cb6378a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-188a01d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"188a01d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d95852e\" data-id=\"d95852e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-361110c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"361110c\" data-element_type=\"section\" data-e-type=\"section\" id=\"serviceunion21B2\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22ca504\" data-id=\"22ca504\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd5be34 elementor-widget elementor-widget-image\" data-id=\"fd5be34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"121\" src=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png\" class=\"attachment-medium_large size-medium_large wp-image-5233\" alt=\"ServiceUnion\" srcset=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png 768w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150-300x47.png 300w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150-1024x162.png 1024w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150.png 1195w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bd1c7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bd1c7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e0cb5e\" data-id=\"9e0cb5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e29cbc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e29cbc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5485048\" data-id=\"5485048\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da0da92 elementor-widget elementor-widget-heading\" data-id=\"da0da92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">UNSERE SPEZIALISTEN \u2013 IMMER AN IHRER SEITE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93dbb47 elementor-widget elementor-widget-text-editor\" data-id=\"93dbb47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Mechatroniker, Bauingenieure, Elektriker, Maschinenbauer, Heizungsbauer, Landwirte, Verfahrenstechniker, Agraringenieure, Biologen, Landmaschinenmechaniker, Ingenieure, Techniker (m\/w\/d) sind f\u00fcr Sie da:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75c0148 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75c0148\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-004b8a2\" data-id=\"004b8a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f79de8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4f79de8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 170.98 164.54\" style=\"enable-background:new 0 0 170.98 164.54;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:#FFFFFF;}\t.st1{fill:#AFB6BA;}\t.st2{fill:#575756;}\t.st3{fill:#65B32E;}\t.st4{fill:#30383B;}<\/style><path class=\"st0\" d=\"M74.52,149.19c31.86,0,57.7-25.83,57.7-57.7c0-31.87-25.83-57.7-57.7-57.7s-57.7,25.83-57.7,57.7  C16.82,123.36,42.65,149.19,74.52,149.19\"><\/path><path class=\"st2\" d=\"M74.52,156.69c-35.95,0-65.2-29.25-65.2-65.2s29.25-65.2,65.2-65.2s65.2,29.25,65.2,65.2  S110.47,156.69,74.52,156.69z M74.52,41.3c-27.68,0-50.2,22.52-50.2,50.2s22.52,50.2,50.2,50.2s50.2-22.52,50.2-50.2  S102.2,41.3,74.52,41.3z\"><\/path><path class=\"st3\" d=\"M73.11,127.67c-0.08,0-0.15,0-0.23,0c-3.2-0.07-6.17-1.68-7.99-4.31L38.35,85.01  c-3.14-4.54-2.01-10.77,2.53-13.91s10.77-2.01,13.91,2.53l18.7,27.03l66.64-87.42c3.35-4.39,9.62-5.24,14.02-1.89  c4.39,3.35,5.24,9.62,1.89,14.02l-74.98,98.37C79.16,126.21,76.22,127.67,73.11,127.67z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"elementor-icon-list-text\"><strong>BHKW-Service<\/strong><br \/> Inspektion, Pflege, Wartung, Instandsetzung und Notf\u00e4lle. Ersatz von Verschlei\u00dfteilen, Verbrauchsmaterial, Tauschmotoren, Fernwartung und -\u00fcberwachung, \u00d6lanalysen, usw.<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 170.98 164.54\" style=\"enable-background:new 0 0 170.98 164.54;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:#FFFFFF;}\t.st1{fill:#AFB6BA;}\t.st2{fill:#575756;}\t.st3{fill:#65B32E;}\t.st4{fill:#30383B;}<\/style><path class=\"st0\" d=\"M74.52,149.19c31.86,0,57.7-25.83,57.7-57.7c0-31.87-25.83-57.7-57.7-57.7s-57.7,25.83-57.7,57.7  C16.82,123.36,42.65,149.19,74.52,149.19\"><\/path><path class=\"st2\" d=\"M74.52,156.69c-35.95,0-65.2-29.25-65.2-65.2s29.25-65.2,65.2-65.2s65.2,29.25,65.2,65.2  S110.47,156.69,74.52,156.69z M74.52,41.3c-27.68,0-50.2,22.52-50.2,50.2s22.52,50.2,50.2,50.2s50.2-22.52,50.2-50.2  S102.2,41.3,74.52,41.3z\"><\/path><path class=\"st3\" d=\"M73.11,127.67c-0.08,0-0.15,0-0.23,0c-3.2-0.07-6.17-1.68-7.99-4.31L38.35,85.01  c-3.14-4.54-2.01-10.77,2.53-13.91s10.77-2.01,13.91,2.53l18.7,27.03l66.64-87.42c3.35-4.39,9.62-5.24,14.02-1.89  c4.39,3.35,5.24,9.62,1.89,14.02l-74.98,98.37C79.16,126.21,76.22,127.67,73.11,127.67z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"elementor-icon-list-text\"><strong>Anlagen-Service<\/strong><br \/> Biologische und technische Beratung, Pflege, Wartung, Inspektion und vorbeugende Instandhaltungsma\u00dfnahmen der Anlagentechnik.<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 170.98 164.54\" style=\"enable-background:new 0 0 170.98 164.54;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:#FFFFFF;}\t.st1{fill:#AFB6BA;}\t.st2{fill:#575756;}\t.st3{fill:#65B32E;}\t.st4{fill:#30383B;}<\/style><path class=\"st0\" d=\"M74.52,149.19c31.86,0,57.7-25.83,57.7-57.7c0-31.87-25.83-57.7-57.7-57.7s-57.7,25.83-57.7,57.7  C16.82,123.36,42.65,149.19,74.52,149.19\"><\/path><path class=\"st2\" d=\"M74.52,156.69c-35.95,0-65.2-29.25-65.2-65.2s29.25-65.2,65.2-65.2s65.2,29.25,65.2,65.2  S110.47,156.69,74.52,156.69z M74.52,41.3c-27.68,0-50.2,22.52-50.2,50.2s22.52,50.2,50.2,50.2s50.2-22.52,50.2-50.2  S102.2,41.3,74.52,41.3z\"><\/path><path class=\"st3\" d=\"M73.11,127.67c-0.08,0-0.15,0-0.23,0c-3.2-0.07-6.17-1.68-7.99-4.31L38.35,85.01  c-3.14-4.54-2.01-10.77,2.53-13.91s10.77-2.01,13.91,2.53l18.7,27.03l66.64-87.42c3.35-4.39,9.62-5.24,14.02-1.89  c4.39,3.35,5.24,9.62,1.89,14.02l-74.98,98.37C79.16,126.21,76.22,127.67,73.11,127.67z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"elementor-icon-list-text\"><strong>Elektro-Service<\/strong><br \/> Beratung, Einbindung, Pr\u00fcfung und Service rund um die Elektrotechnik sowie Steuerung der Anlage und BHKW.<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef307d1 elementor-widget elementor-widget-spacer\" data-id=\"ef307d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9bb041\" data-id=\"e9bb041\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55e1cb3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"55e1cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 170.98 164.54\" style=\"enable-background:new 0 0 170.98 164.54;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:#FFFFFF;}\t.st1{fill:#AFB6BA;}\t.st2{fill:#575756;}\t.st3{fill:#65B32E;}\t.st4{fill:#30383B;}<\/style><path class=\"st0\" d=\"M74.52,149.19c31.86,0,57.7-25.83,57.7-57.7c0-31.87-25.83-57.7-57.7-57.7s-57.7,25.83-57.7,57.7  C16.82,123.36,42.65,149.19,74.52,149.19\"><\/path><path class=\"st2\" d=\"M74.52,156.69c-35.95,0-65.2-29.25-65.2-65.2s29.25-65.2,65.2-65.2s65.2,29.25,65.2,65.2  S110.47,156.69,74.52,156.69z M74.52,41.3c-27.68,0-50.2,22.52-50.2,50.2s22.52,50.2,50.2,50.2s50.2-22.52,50.2-50.2  S102.2,41.3,74.52,41.3z\"><\/path><path class=\"st3\" d=\"M73.11,127.67c-0.08,0-0.15,0-0.23,0c-3.2-0.07-6.17-1.68-7.99-4.31L38.35,85.01  c-3.14-4.54-2.01-10.77,2.53-13.91s10.77-2.01,13.91,2.53l18.7,27.03l66.64-87.42c3.35-4.39,9.62-5.24,14.02-1.89  c4.39,3.35,5.24,9.62,1.89,14.02l-74.98,98.37C79.16,126.21,76.22,127.67,73.11,127.67z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"elementor-icon-list-text\"><strong>Labor-Service<\/strong><br \/> Analyse- und G\u00e4rversuchslabor zur Ermittlung von Restgas und Substratpotenzialen und Kontrolle der Fermenterbiologie, Additive, Prozessoptimierung, usw.<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 170.98 164.54\" style=\"enable-background:new 0 0 170.98 164.54;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:#FFFFFF;}\t.st1{fill:#AFB6BA;}\t.st2{fill:#575756;}\t.st3{fill:#65B32E;}\t.st4{fill:#30383B;}<\/style><path class=\"st0\" d=\"M74.52,149.19c31.86,0,57.7-25.83,57.7-57.7c0-31.87-25.83-57.7-57.7-57.7s-57.7,25.83-57.7,57.7  C16.82,123.36,42.65,149.19,74.52,149.19\"><\/path><path class=\"st2\" d=\"M74.52,156.69c-35.95,0-65.2-29.25-65.2-65.2s29.25-65.2,65.2-65.2s65.2,29.25,65.2,65.2  S110.47,156.69,74.52,156.69z M74.52,41.3c-27.68,0-50.2,22.52-50.2,50.2s22.52,50.2,50.2,50.2s50.2-22.52,50.2-50.2  S102.2,41.3,74.52,41.3z\"><\/path><path class=\"st3\" d=\"M73.11,127.67c-0.08,0-0.15,0-0.23,0c-3.2-0.07-6.17-1.68-7.99-4.31L38.35,85.01  c-3.14-4.54-2.01-10.77,2.53-13.91s10.77-2.01,13.91,2.53l18.7,27.03l66.64-87.42c3.35-4.39,9.62-5.24,14.02-1.89  c4.39,3.35,5.24,9.62,1.89,14.02l-74.98,98.37C79.16,126.21,76.22,127.67,73.11,127.67z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"elementor-icon-list-text\"><strong>Repowering<\/strong><br \/> Beh\u00e4lterrevision, BHKW-Motorentausch, R\u00fchrwerkstausch, Wechsel Gasspeicher, Flexibilisierung, Prozessoptimierung, Senkung Eigenstromverbrauch, Erweiterungen aller Art, usw.<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 170.98 164.54\" style=\"enable-background:new 0 0 170.98 164.54;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:#FFFFFF;}\t.st1{fill:#AFB6BA;}\t.st2{fill:#575756;}\t.st3{fill:#65B32E;}\t.st4{fill:#30383B;}<\/style><path class=\"st0\" d=\"M74.52,149.19c31.86,0,57.7-25.83,57.7-57.7c0-31.87-25.83-57.7-57.7-57.7s-57.7,25.83-57.7,57.7  C16.82,123.36,42.65,149.19,74.52,149.19\"><\/path><path class=\"st2\" d=\"M74.52,156.69c-35.95,0-65.2-29.25-65.2-65.2s29.25-65.2,65.2-65.2s65.2,29.25,65.2,65.2  S110.47,156.69,74.52,156.69z M74.52,41.3c-27.68,0-50.2,22.52-50.2,50.2s22.52,50.2,50.2,50.2s50.2-22.52,50.2-50.2  S102.2,41.3,74.52,41.3z\"><\/path><path class=\"st3\" d=\"M73.11,127.67c-0.08,0-0.15,0-0.23,0c-3.2-0.07-6.17-1.68-7.99-4.31L38.35,85.01  c-3.14-4.54-2.01-10.77,2.53-13.91s10.77-2.01,13.91,2.53l18.7,27.03l66.64-87.42c3.35-4.39,9.62-5.24,14.02-1.89  c4.39,3.35,5.24,9.62,1.89,14.02l-74.98,98.37C79.16,126.21,76.22,127.67,73.11,127.67z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"elementor-icon-list-text\"><strong> Planung &amp; Genehmigung<\/strong><br \/> Unser hauseigenes Planungsb\u00fcro unterst\u00fctzt Sie umfassend in allen Belangen, z.B. bei Bau- und Genehmigungsantr\u00e4gen, Ex-Zonen-Pl\u00e4ne, Havariekonzepte, uvm.<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fb0f4d elementor-widget elementor-widget-spacer\" data-id=\"1fb0f4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09d033f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09d033f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0561298\" data-id=\"0561298\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69c3a01 elementor-widget elementor-widget-heading\" data-id=\"69c3a01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Der perfekte Zusatz f\u00fcr Ihre Anlage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0429227 elementor-widget elementor-widget-text-editor\" data-id=\"0429227\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIhr regionaler Partner, wenn es um Wartung, Instandhaltung, Reparatur, Repowering und Erweiterung Ihrer Anlage geht.<br\/>\n\n<em>Ihr regionaler Partner. Rund um Biogas. Bundesweit.<\/em>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa427f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1aa427f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.serviceunion.de\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HIER GEHTS ZUR SERVICEUNION<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-addca29 elementor-widget elementor-widget-spacer\" data-id=\"addca29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8aecec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8aecec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56605ed\" data-id=\"56605ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75d502c elementor-widget elementor-widget-spacer\" data-id=\"75d502c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb1d74c elementor-widget elementor-widget-heading\" data-id=\"eb1d74c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fachkundig und sicher \u2013 Wir haben den plan f\u00fcr Sie!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2bf829 elementor-widget elementor-widget-spacer\" data-id=\"f2bf829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea5957a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea5957a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d15a14e\" data-id=\"d15a14e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-366f4cd elementor-widget elementor-widget-text-editor\" data-id=\"366f4cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir unterst\u00fctzen Sie bei der Standortsuche, erstellen Vorentw\u00fcrfe und erarbeiten eine f\u00fcr Sie ma\u00dfgeschneiderte Anlagenauslegung. Wenn Sie es m\u00f6chten, bereiten wir den Bauantrag f\u00fcr Ihre Biogasanlage vor und unterst\u00fctzen Sie fachkundig bei der Erstellung der erforderlichen externen individuellen Gutachten und stehen Ihnen bei Beh\u00f6rdeng\u00e4ngen, Abstimmungen mit Sachverst\u00e4ndigen oder Fragen zum Energieversorger zur Seite.<\/p><p>In allen Belangen rund um Planung &amp; Genehmigung unterst\u00fctzt Sie unser Netzwerk-Partner, die ServiceUnion GmbH.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6977d6f\" data-id=\"6977d6f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a218d90 elementor-widget elementor-widget-spacer\" data-id=\"a218d90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2230132 elementor-widget elementor-widget-spacer\" data-id=\"2230132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff4938e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff4938e\" data-element_type=\"section\" data-e-type=\"section\" id=\"finanzierung21B2\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f3091c\" data-id=\"7f3091c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7ba0c2 elementor-widget elementor-widget-spacer\" data-id=\"a7ba0c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0f8c52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0f8c52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-190ccd1\" data-id=\"190ccd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c34ed8 elementor-widget elementor-widget-image\" data-id=\"9c34ed8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"200\" src=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/12\/Farmers-Happiness_Logo-1-1-768x200.png\" class=\"attachment-medium_large size-medium_large wp-image-2372\" alt=\"Farmers Happiness Logo\" srcset=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/12\/Farmers-Happiness_Logo-1-1-768x200.png 768w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/12\/Farmers-Happiness_Logo-1-1-300x78.png 300w, https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/12\/Farmers-Happiness_Logo-1-1.png 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e80cd0e\" data-id=\"e80cd0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d5172a elementor-widget elementor-widget-heading\" data-id=\"5d5172a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Finanzierung und Betreibermodell <br> wir finden Mittel und Wege!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79d63ac elementor-widget elementor-widget-text-editor\" data-id=\"79d63ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Auf Grundlage einer Wirtschaftlichkeitsberechnung k\u00f6nnen wir Sie bei der Beurteilung unterst\u00fctzen, ob das Projekt die gew\u00fcnschten Ergebnisse liefern kann.<br \/>Nach unserer Erfahrung lassen sich Biogas-Projekte auch ohne bank\u00fcbliche Sicherheiten und ohne gro\u00dfen Eigenkapitalanteil realisieren. Bei der Suche nach einer geeigneten Finanzierung kooperieren wir sehr eng mit der <a style=\"color: #ffffff;\" href=\"https:\/\/www.farmers-happiness.de\/\" target=\"_blank\" rel=\"noopener\">Farmers Happiness GmbH <\/a>mit Sitz in Ismaning. Die Farmers Happiness GmbH unterst\u00fctzt Sie bei der Suche nach der f\u00fcr Sie passenden Finanzierungsform oder -alternative und kann dabei auf ein gro\u00dfes Banken-, Leasing- und Investoren-Netzwerk zur\u00fcckgreifen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-422950b elementor-widget elementor-widget-spacer\" data-id=\"422950b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4718f7f elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"4718f7f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7106a48\" data-id=\"7106a48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f406b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f406b0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-583caa9\" data-id=\"583caa9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ae8ef2 elementor-widget elementor-widget-spacer\" data-id=\"7ae8ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dienstleistungen Serviceleistungen vom ersten Tag an Legt man eine Laufzeit von mindestens 20 Jahren f\u00fcr eine Biogasanlage zu Grunde, dann wird deutlich, welchen Stellenwert ein zuverl\u00e4ssiger Servicepartner f\u00fcr das Betriebsergebnis hat. DIENSTLEISTUNGEN SERVICEUNION FINANZIERUNG ALLES AUS EINER HAND \u2013 DARAUF IST VERLASS! Langfristig entscheiden hochwertige Technik, zuverl\u00e4ssiger Service und konti\u00adnuierliche Updates \u00fcber die Rentabilit\u00e4t Ihrer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-105","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>agriKomp GmbH - Serviceleistungen aus einer Hand<\/title>\n<meta name=\"description\" content=\"Langfristig entscheidenhochwertige Technik, zuverl\u00e4ssiger Service undkontinuierliche Updates \u00fcber die Rentabilit\u00e4t Ihrer Biogasanlage.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serviceleistungen aus einer Hand\" \/>\n<meta property=\"og:description\" content=\"Legt man eine Laufzeit von mindestens 20 Jahren f\u00fcr eine Biogasanlage zu Grunde, dann wird deutlich, welchen Stellenwert ein zuverl\u00e4ssiger Servicepartner f\u00fcr das Betriebsergebnis hat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/\" \/>\n<meta property=\"og:site_name\" content=\"agriKomp GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agriKomp.Deutschland\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-18T09:43:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/service-dienstleistungen-web-e1619437208725.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"433\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Serviceleistungen aus einer Hand\" \/>\n<meta name=\"twitter:description\" content=\"Legt man eine Laufzeit von mindestens 20 Jahren f\u00fcr eine Biogasanlage zu Grunde, dann wird deutlich, welchen Stellenwert ein zuverl\u00e4ssiger Servicepartner f\u00fcr das Betriebsergebnis hat.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/service-dienstleistungen-web-e1619437208725.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/\",\"url\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/\",\"name\":\"agriKomp GmbH - Serviceleistungen aus einer Hand\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png\",\"datePublished\":\"2020-11-16T14:46:34+00:00\",\"dateModified\":\"2024-12-18T09:43:03+00:00\",\"description\":\"Langfristig entscheidenhochwertige Technik, zuverl\u00e4ssiger Service undkontinuierliche Updates \u00fcber die Rentabilit\u00e4t Ihrer Biogasanlage.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png\",\"contentUrl\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/dienstleistungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/www.agrikomp.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dienstleistungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/\",\"name\":\"agriKomp GmbH\",\"description\":\"Biogasanlagen und Biogastechnik wie sie gebraucht wird\",\"publisher\":{\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#organization\",\"name\":\"agriKomp\",\"url\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/150224_aKlogo-grau_quer.png\",\"contentUrl\":\"https:\\\/\\\/www.agrikomp.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/150224_aKlogo-grau_quer.png\",\"width\":2712,\"height\":482,\"caption\":\"agriKomp\"},\"image\":{\"@id\":\"https:\\\/\\\/agrikomp.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agriKomp.Deutschland\",\"https:\\\/\\\/www.instagram.com\\\/agrikomp\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/5254243\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@AgrikompDeutschland\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"agriKomp GmbH - Serviceleistungen aus einer Hand","description":"Langfristig entscheidenhochwertige Technik, zuverl\u00e4ssiger Service undkontinuierliche Updates \u00fcber die Rentabilit\u00e4t Ihrer Biogasanlage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/","og_locale":"de_DE","og_type":"article","og_title":"Serviceleistungen aus einer Hand","og_description":"Legt man eine Laufzeit von mindestens 20 Jahren f\u00fcr eine Biogasanlage zu Grunde, dann wird deutlich, welchen Stellenwert ein zuverl\u00e4ssiger Servicepartner f\u00fcr das Betriebsergebnis hat.","og_url":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/","og_site_name":"agriKomp GmbH","article_publisher":"https:\/\/www.facebook.com\/agriKomp.Deutschland","article_modified_time":"2024-12-18T09:43:03+00:00","og_image":[{"width":433,"height":422,"url":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/service-dienstleistungen-web-e1619437208725.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Serviceleistungen aus einer Hand","twitter_description":"Legt man eine Laufzeit von mindestens 20 Jahren f\u00fcr eine Biogasanlage zu Grunde, dann wird deutlich, welchen Stellenwert ein zuverl\u00e4ssiger Servicepartner f\u00fcr das Betriebsergebnis hat.","twitter_image":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/service-dienstleistungen-web-e1619437208725.jpg","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/","url":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/","name":"agriKomp GmbH - Serviceleistungen aus einer Hand","isPartOf":{"@id":"https:\/\/agrikomp.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/#primaryimage"},"image":{"@id":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png","datePublished":"2020-11-16T14:46:34+00:00","dateModified":"2024-12-18T09:43:03+00:00","description":"Langfristig entscheidenhochwertige Technik, zuverl\u00e4ssiger Service undkontinuierliche Updates \u00fcber die Rentabilit\u00e4t Ihrer Biogasanlage.","breadcrumb":{"@id":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.agrikomp.com\/de\/dienstleistungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/#primaryimage","url":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png","contentUrl":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2021\/03\/160601_su-serviceunion-logo-weiss-e1619436642150-768x121.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.agrikomp.com\/de\/dienstleistungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/www.agrikomp.com\/de\/"},{"@type":"ListItem","position":2,"name":"Dienstleistungen"}]},{"@type":"WebSite","@id":"https:\/\/agrikomp.com\/de\/#website","url":"https:\/\/agrikomp.com\/de\/","name":"agriKomp GmbH","description":"Biogasanlagen und Biogastechnik wie sie gebraucht wird","publisher":{"@id":"https:\/\/agrikomp.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrikomp.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/agrikomp.com\/de\/#organization","name":"agriKomp","url":"https:\/\/agrikomp.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/agrikomp.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/11\/150224_aKlogo-grau_quer.png","contentUrl":"https:\/\/www.agrikomp.com\/wp-content\/uploads\/2020\/11\/150224_aKlogo-grau_quer.png","width":2712,"height":482,"caption":"agriKomp"},"image":{"@id":"https:\/\/agrikomp.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agriKomp.Deutschland","https:\/\/www.instagram.com\/agrikomp\/?hl=en","https:\/\/www.linkedin.com\/company\/5254243\/","https:\/\/www.youtube.com\/@AgrikompDeutschland"]}]}},"_links":{"self":[{"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/pages\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/comments?post=105"}],"version-history":[{"count":44,"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/pages\/105\/revisions"}],"predecessor-version":[{"id":41249,"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/pages\/105\/revisions\/41249"}],"wp:attachment":[{"href":"https:\/\/www.agrikomp.com\/de\/wp-json\/wp\/v2\/media?parent=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}